{"id":9361,"date":"2022-10-19T21:57:35","date_gmt":"2022-10-19T19:57:35","guid":{"rendered":"https:\/\/www.blanquer.com\/producto\/grisard\/"},"modified":"2022-10-19T21:57:35","modified_gmt":"2022-10-19T19:57:35","slug":"grisard","status":"publish","type":"product","link":"https:\/\/www.blanquer.com\/en\/producto\/grisard\/","title":{"rendered":"Grisard"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td class=\"field\">Name<\/td>\n<td>Grisard<\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Scientific<\/td>\n<p> name<\/p>\n<td>Populus \u00d7 canescens, (Aiton) Sm.<\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Origin<\/td>\n<td>Europe.<\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Type<\/td>\n<td>Lisa.<\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Format<\/td>\n<td>Sheet metal.<\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Density<\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td class=\"field\">Product Description<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>SEE PDF FILE: GRISARD<\/p>\n","protected":false},"featured_media":9362,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[508],"product_tag":[496,893,913,470,482,468],"class_list":["post-9361","product","type-product","status-publish","has-post-thumbnail","product_cat-species","product_tag-badge","product_tag-buy-now","product_tag-grisard","product_tag-sale","product_tag-warehouse","product_tag-wood","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/product\/9361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/media\/9362"}],"wp:attachment":[{"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/media?parent=9361"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/product_brand?post=9361"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/product_cat?post=9361"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.blanquer.com\/en\/wp-json\/wp\/v2\/product_tag?post=9361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}